{"id":22481,"date":"2011-09-02T14:58:23","date_gmt":"2011-09-02T19:28:23","guid":{"rendered":"http:\/\/piel-l.org\/blog\/?p=22481"},"modified":"2011-09-02T14:58:23","modified_gmt":"2011-09-02T19:28:23","slug":"nuevas-drogas-nuevas-reacciones","status":"publish","type":"post","link":"https:\/\/piel-l.org\/blog\/22481","title":{"rendered":"Nuevas drogas, nuevas reacciones"},"content":{"rendered":"<p><em><a href=\"http:\/\/lh6.ggpht.com\/-lZ3BBVNSbxM\/TlwJxua_ifI\/AAAAAAAAAvY\/SGX5iH980nc\/omar.JPG?imgmax=640\" rel=\"lightbox[2011-8-5-14-57-17]\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/lh6.ggpht.com\/-lZ3BBVNSbxM\/TlwJxua_ifI\/AAAAAAAAAvY\/SGX5iH980nc\/s64-c\/omar.JPG\" alt=\"omar.JPG\" width=\"64\" height=\"64\" \/><\/a><br \/>Conferencias magistrales<br \/><\/em><strong>Apunte de conferencia magistral: Omar sangueza North Carolina, USA<\/strong><\/p>\n<p><!--more--><\/p>\n<p>\u2022 Inhibidores del Factor de necrosis tumoral alfa (TNF-alfa)<\/p>\n<p>Etanercept (Enbrel, Immunex, EE.UU.), Es un biologico un recombinante del receptor de TNF-alfa soluble fusionado con el fragmento Fc de IgG2.<\/p>\n<p>Adalimumab (Humira), un recombinante humano anticuerpo monoclonal IgG1<\/p>\n<p>\u2022 Donde se utilizan?<\/p>\n<ul>\n<li>Psoriasis<\/li>\n<li>Artritis reumatoide<\/li>\n<li>Enfermedad del tejido conectivo<\/li>\n<li>Eenfermedad de Crohn<\/li>\n<\/ul>\n<p>Rreacciones Infliximab (Remicade)<\/p>\n<p>Dermatitis psoriasiforme<\/p>\n<p>Vasculitis leucocitocl\u00e1stica<\/p>\n<p>Granuloma anular<\/p>\n<p>Pernio-como erupci\u00f3n<\/p>\n<p>Erupci\u00f3n pustulosa<\/p>\n<p>Eritema nudoso<\/p>\n<p>Sarcoidosis<\/p>\n<p>Nevus melanoc\u00edticoseruptivos<\/p>\n<p>Queratoacantomasm\u00faltiples<\/p>\n<p>Reacciones del Embrel<\/p>\n<p>Urticaria<\/p>\n<p>Celulitis<\/p>\n<p>Vasculitis leucocitocl\u00e1stica<\/p>\n<p>Eritema multiforme<\/p>\n<p>Dermatitis psoriasiforme<\/p>\n<p>Granuloma anular<\/p>\n<p>M\u00faltiples lentigos<\/p>\n<p>Reacciones de Humira (Adalimumab)<\/p>\n<p>Vasculitis leucocitocl\u00e1stica<\/p>\n<p>Dermatitis psoriasiforme<\/p>\n<p>Pustulosis \/ Erupci\u00f3n acneiforme<\/p>\n<p>Granuloma anular \/ dermatitis granulomatosa intersticial<\/p>\n<p>lupus eritematoso erupci\u00f3n-like<\/p>\n<p>Granulocitos macr\u00f3fagos factor estimulante de colonias (GMCSF), es una citoquina que estimula el crecimiento de las c\u00e9lulas madre pluripotenciales de la m\u00e9dula resultando en un aumento en el n\u00famero de neutr\u00f3filos, eosin\u00f3filos y macr\u00f3fagos.<\/p>\n<p>Generalizada o difusa erupci\u00f3n<\/p>\n<p>Reacci\u00f3n cut\u00e1nea local<\/p>\n<p>Dermatosis neutrof\u00edlica<\/p>\n<p>Epidermolisis bullosa<\/p>\n<p>Vasculitis<\/p>\n<p>Foliculitis<\/p>\n<p>Andelastophagocytosis<\/p>\n<p>Interfer\u00f3n: , una familia de glicoprote\u00ednas de secreci\u00f3n, es un agente de modulaci\u00f3n inmune que se utiliza en el tratamiento de tumores, infecciones virales, como hepatitis C cr\u00f3nica, y enfermedades inflamatorias como la esclerosis m\u00faltiple.<\/p>\n<p>Reacci\u00f3n en el sitio de inyecci\u00f3n<\/p>\n<p>Psoriasis<\/p>\n<p>Sarcoidosis<\/p>\n<p>Alopecia<\/p>\n<p>Vitiligo<\/p>\n<p>Otros incluyendo exantema fijo, erupci\u00f3n liquenoide y lupus eritematoso<\/p>\n<p>Factor de crecimiento epid\u00e9rmico receptor de serotonina (Erbitux \/ Cetuximab) es un miembro de la quinasa del receptor de la tirosina Erb-B (CT) de la familia que incluye ErbB-2, ErbB-3 y ErbB-4.Cetuximab O, gefitinib, erlotinib, y son la Administraci\u00f3n de Alimentos y Medicamentos (FDA) ha aprobado para pacientes con c\u00e1ncer de pulm\u00f3n de c\u00e9lulas no peque\u00f1as y el colorrectal, o que presentan intolerancia a la quimioterapia.<\/p>\n<p>Panitumumab es un anticuerpo monoclonal IgG2 totalmente humano dirigido al receptor del EGF (EGFR).velocidad de reacci\u00f3n de hipersensibilidad es baja en comparaci\u00f3n con cetuximab.<\/p>\n<p>Erupci\u00f3n acneiforme<\/p>\n<p>Paroniquia y la anormalidad del pelo<\/p>\n<p>Quinasa (sorafenib, sunitinib) Sorafenib es un inhibidor de tosilato multiquinasa oral con actividad de amplio espectro contra los productos de tipo salvaje del gen de la RAF, V599-E mutante BRAF, m\u00faltiples receptores de tirosina quinasa del receptor vascular de la familia como factor de crecimiento endotelial (VEGFR-1, 2, 3), crecimiento derivado de plaquetas factor de la familia del receptor (PDGFR-beta), las c\u00e9lulas madre del receptor de factor de crecimiento (c-KIT), similar al FMS tyrosine6kinase 3 (Flt-3), y el receptor codificado por el protooncog\u00e9n RET (RET) es aprobado por la FDA para el tratamiento de tumores del estroma gastrointestinal despu\u00e9s del fracaso del tratamiento con imatinib y carcinoma de c\u00e9lulas renales avanzado.Se utiliza actualmente en ensayos cl\u00ednicos para el tratamiento de tumores s\u00f3lidos, incluyendo el melanoma y no peque\u00f1as carcinomas de pulm\u00f3n de c\u00e9lulas.<\/p>\n<p>Reaccion en pies y manos<\/p>\n<p>Queratoacantoma m\u00faltiple de tipo carcinoma de c\u00e9lulas escamosas<\/p>\n<p>Eruptivas nevus melanoc\u00edticos<\/p>\n<p>Erupci\u00f3n no especifica<\/p>\n<p>Cambios en pelos y u\u00f1as<\/p>\n<p>Imiquimod (Aldara): inmunomodulador para el tratamiento de las verrugas genitales, queratosis act\u00ednica y carcinomas de c\u00e9lulas basales. Tambi\u00e9n se ha utilizado \u201cOff label\u201d para otros tumores malignos, incluyendo micosis fungoide, la enfermedad de Bowen, y lentigo maligno.A la penetraci\u00f3n de la epidermis, dermis imiquimod se une a las c\u00e9lulas dendr\u00edticas y los macr\u00f3fagos a trav\u00e9s de Toll-like receptor (TLR) -7, lo que resulta en la liberaci\u00f3n de citocinas proinflamatorias como el interfer\u00f3n (IFN)-un factor-a de necrosis tumoral, entre otras-leucina (IL) -2, IL-6 y IL-8<\/p>\n<p>Lupus eritematoso de reacci\u00f3n en la piel tratada con imiquimod: aportaci\u00f3n de 2 casos May P. Chan, MD and Mary Jane Zimarowski, MD<\/p>\n<p>(Am J Dermatopathol 2011;0:000\u2013000)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conferencias magistralesApunte de conferencia magistral: Omar sangueza North Carolina, USA<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[127,49,285],"tags":[],"class_list":["post-22481","post","type-post","status-publish","format-standard","","category-gtd-seccion-venezuela","category-conferencias","category-ecos-de-congresos"],"_links":{"self":[{"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/posts\/22481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/comments?post=22481"}],"version-history":[{"count":0,"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/posts\/22481\/revisions"}],"wp:attachment":[{"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/media?parent=22481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/categories?post=22481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/piel-l.org\/blog\/wp-json\/wp\/v2\/tags?post=22481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}